{"id":7973,"date":"2019-11-19T08:50:55","date_gmt":"2019-11-19T07:50:55","guid":{"rendered":"https:\/\/osg-excello.com\/impressum\/"},"modified":"2025-07-03T07:20:19","modified_gmt":"2025-07-03T05:20:19","slug":"impressum","status":"publish","type":"page","link":"https:\/\/osg-excello.com\/it\/impressum\/","title":{"rendered":"impronta"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-807no-33a4a38e5e0d5dea70cde682a9dc653a\">\n.flex_column.av-807no-33a4a38e5e0d5dea70cde682a9dc653a{\nborder-radius:0px 0px 0px 0px;\npadding:25px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-807no-33a4a38e5e0d5dea70cde682a9dc653a av_one_full  avia-builder-el-0  el_before_av_hr  avia-builder-el-first  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k3e92cn2-7a59c4d3412d14d5caac4f6bef0d3409\">\n#top .av-special-heading.av-k3e92cn2-7a59c4d3412d14d5caac4f6bef0d3409{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-k3e92cn2-7a59c4d3412d14d5caac4f6bef0d3409 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-k3e92cn2-7a59c4d3412d14d5caac4f6bef0d3409 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-k3e92cn2-7a59c4d3412d14d5caac4f6bef0d3409 av-special-heading-h1 blockquote modern-quote modern-centered  avia-builder-el-1  avia-builder-el-no-sibling '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >impronta<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k363cjsl-6c3a36cc1ad2d24930cc419f13ab6bc6\">\n#top .hr.av-k363cjsl-6c3a36cc1ad2d24930cc419f13ab6bc6{\nmargin-top:0px;\nmargin-bottom:30px;\n}\n.hr.av-k363cjsl-6c3a36cc1ad2d24930cc419f13ab6bc6 .hr-inner{\nwidth:30%;\nborder-color:#e8e8e8;\nmax-width:45%;\n}\n.hr.av-k363cjsl-6c3a36cc1ad2d24930cc419f13ab6bc6 .av-seperator-icon{\ncolor:#e8e8e8;\n}\n.hr.av-k363cjsl-6c3a36cc1ad2d24930cc419f13ab6bc6 .av-seperator-icon.avia-svg-icon svg:first-child{\nfill:#e8e8e8;\nstroke:#e8e8e8;\n}\n<\/style>\n<div  class='hr av-k363cjsl-6c3a36cc1ad2d24930cc419f13ab6bc6 hr-custom  avia-builder-el-2  el_after_av_one_full  el_before_av_section  avia-builder-el-last  hr-center hr-icon-yes'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><span class='av-seperator-icon avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue898' data-av_iconfont='entypo-fontello' ><\/span><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k3647wxa-14f501a09e84162727fa6ec184c7a00c\">\n.avia-section.av-k3647wxa-14f501a09e84162727fa6ec184c7a00c{\nmargin-top:0px;\nmargin-bottom:100px;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-k3647wxa-14f501a09e84162727fa6ec184c7a00c main_color avia-section-no-padding avia-no-border-styling  avia-builder-el-3  el_after_av_hr  el_before_av_one_third  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-7973'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2xr7s-a11a412b0a34fb6131499ee57be96de4\">\n.flex_column.av-2xr7s-a11a412b0a34fb6131499ee57be96de4{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-2xr7s-a11a412b0a34fb6131499ee57be96de4 av_two_third  avia-builder-el-4  el_before_av_one_third  avia-builder-el-first  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><section  class='av_textblock_section av-k3e98net-ad2e479a713aae4079db3fed0d08f09d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>Operatore del sito ai sensi del \u00a7 5 della legge tedesca sui media telematici<\/h3>\n<p>OSG EX-CELL-O GmbH<br \/>\nSteinbeisstrasse 16<br \/>\n73037 G\u00f6ppingen<br \/>\nTel. +49 71 61 15840-0<br \/>\nE-Mail: <a href=\"mailto:info@osg-excello.com\">info@osg-excello.com<\/a><\/p>\n<p><strong>Registro di commercio<\/strong><br \/>\nTribunale del registro: Tribunale distrettuale di Ulm<br \/>\nNumero di registro: HRB 739 202  <\/p>\n<p><strong>Direttori esecutivi:<\/strong><br \/>\nHideaki Osawa, Oliver Schunter, Juergen Schmid, Takehiro Kamiya<\/p>\n<p><strong>Numero di identificazione IVA ai sensi del \u00a7 27a della legge sull&#8217;IVA:<br \/>\n<\/strong>DE 327006530<\/p>\n<h3>Responsabile del contenuto ai sensi del \u00a7 55 comma 2 RStV:<\/h3>\n<p>J\u00fcrgen Schmid<br \/>\nOSG EX-CELL-O GmbH<br \/>\nSteinbeisstrasse 16<br \/>\n73037 G\u00f6ppingen<br \/>\nTel. +49 71 61 15840-0<\/p>\n<h3>Informazioni sulla risoluzione delle controversie online:<\/h3>\n<p>La Commissione europea mette a disposizione una piattaforma per la risoluzione delle controversie online (ODR).<br \/>\nQuesta piattaforma \u00e8 disponibile al seguente link: <a href=\"https:\/\/ec.europa.eu\/consumers\/odr\/\">https:\/\/ec.europa.eu\/consumers\/odr\/<\/a>.<br \/>\nI consumatori possono utilizzare questa piattaforma per risolvere le loro controversie derivanti da contratti online.<\/p>\n<h3>Nota ai sensi del \u00a7 36 VSBG:<\/h3>\n<p>Non parteciperemo a procedure di risoluzione alternativa delle controversie ai sensi del \u00a7 36 VSBG. Il ricorso a un organo arbitrale alternativo non \u00e8 un requisito obbligatorio per il ricorso a un tribunale della giurisdizione competente.<\/p>\n<h3>Copyright e crediti d&#8217;immagine:<\/h3>\n<p>I contenuti di www.osg-excello.com sono protetti dal diritto d&#8217;autore se non indicato diversamente.<br \/>\nLe fotografie utilizzate possono essere contrassegnate da crediti d&#8217;immagine o queste possono essere elencate sotto di esse se non sono nostre immagini.<\/p>\n<p>Le fotografie possono essere utilizzate su siti di terzi solo nei termini della rispettiva licenza di copyright.<\/p>\n<\/div><\/section><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2xr7s-5-17b0eb8128648ded181d065c6c28711e\">\n.flex_column.av-2xr7s-5-17b0eb8128648ded181d065c6c28711e{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-2xr7s-5-17b0eb8128648ded181d065c6c28711e av_one_third  avia-builder-el-6  el_after_av_two_third  avia-builder-el-last  flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><section  class='av_textblock_section av-k3e98net-4-5973b9975ab7843ea92efa826b80ec3c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>Concezione, design e creazione:<\/h3>\n<p><a href=\"https:\/\/AndiHei.com\" target=\"_blank\" rel=\"noopener\">AndiHei.com<\/a><\/p>\n<\/div><\/section><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-7973'><div class='entry-content-wrapper clearfix'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-12jft-33309fbff90adaebba0a96285853c64c\">\n.flex_column.av-12jft-33309fbff90adaebba0a96285853c64c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-12jft-33309fbff90adaebba0a96285853c64c av_one_third  avia-builder-el-8  el_after_av_section  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k360rs33-7cb2379c0dd1ae1a6284b5b131d3067d\">\n.av_font_icon.av-k360rs33-7cb2379c0dd1ae1a6284b5b131d3067d{\ncolor:#ffffff;\nborder-color:#ffffff;\n}\n.avia-svg-icon.av-k360rs33-7cb2379c0dd1ae1a6284b5b131d3067d svg:first-child{\nstroke:#ffffff;\nfill:#ffffff;\n}\n.av_font_icon.av-k360rs33-7cb2379c0dd1ae1a6284b5b131d3067d .av-icon-char{\nfont-size:1px;\nline-height:1px;\n}\n<\/style>\n<span  class='av_font_icon av-k360rs33-7cb2379c0dd1ae1a6284b5b131d3067d avia_animate_when_visible av-icon-style- avia-icon-pos-left avia-iconfont avia-font-entypo-fontello avia-icon-animate'><span class='av-icon-char' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' aria-hidden=\"true\" ><\/span><\/span><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k360rs33-3-448a2d30180abafcc27c51d890fa990e\">\n.av_font_icon.av-k360rs33-3-448a2d30180abafcc27c51d890fa990e{\ncolor:#ffffff;\nborder-color:#ffffff;\n}\n.avia-svg-icon.av-k360rs33-3-448a2d30180abafcc27c51d890fa990e svg:first-child{\nstroke:#ffffff;\nfill:#ffffff;\n}\n.av_font_icon.av-k360rs33-3-448a2d30180abafcc27c51d890fa990e .av-icon-char{\nfont-size:1px;\nline-height:1px;\n}\n<\/style>\n<span  class='av_font_icon av-k360rs33-3-448a2d30180abafcc27c51d890fa990e avia_animate_when_visible av-icon-style- avia-icon-pos-left avia-iconfont avia-font-entypo-fontello avia-icon-animate'><span class='av-icon-char' data-av_icon='\ue854' data-av_iconfont='entypo-fontello' aria-hidden=\"true\" ><\/span><\/span><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k360rs33-2-ba0bfaa88e7f313ec5d2f0eb9a978cb9\">\n.av_font_icon.av-k360rs33-2-ba0bfaa88e7f313ec5d2f0eb9a978cb9{\ncolor:#ffffff;\nborder-color:#ffffff;\n}\n.avia-svg-icon.av-k360rs33-2-ba0bfaa88e7f313ec5d2f0eb9a978cb9 svg:first-child{\nstroke:#ffffff;\nfill:#ffffff;\n}\n.av_font_icon.av-k360rs33-2-ba0bfaa88e7f313ec5d2f0eb9a978cb9 .av-icon-char{\nfont-size:1px;\nline-height:1px;\n}\n<\/style>\n<span  class='av_font_icon av-k360rs33-2-ba0bfaa88e7f313ec5d2f0eb9a978cb9 avia_animate_when_visible av-icon-style- avia-icon-pos-left avia-iconfont avia-font-entypo-fontello avia-icon-animate'><span class='av-icon-char' data-av_icon='\ue838' data-av_iconfont='entypo-fontello' aria-hidden=\"true\" ><\/span><\/span><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k360rs33-1-e9b28f79b61d4a30b9b5f60aaf058a89\">\n.av_font_icon.av-k360rs33-1-e9b28f79b61d4a30b9b5f60aaf058a89{\ncolor:#ffffff;\nborder-color:#ffffff;\n}\n.avia-svg-icon.av-k360rs33-1-e9b28f79b61d4a30b9b5f60aaf058a89 svg:first-child{\nstroke:#ffffff;\nfill:#ffffff;\n}\n.av_font_icon.av-k360rs33-1-e9b28f79b61d4a30b9b5f60aaf058a89 .av-icon-char{\nfont-size:1px;\nline-height:1px;\n}\n<\/style>\n<span  class='av_font_icon av-k360rs33-1-e9b28f79b61d4a30b9b5f60aaf058a89 avia_animate_when_visible av-icon-style- avia-icon-pos-left avia-iconfont avia-font-entypo-fontello avia-icon-animate'><span class='av-icon-char' data-av_icon='\ue86d' data-av_iconfont='entypo-fontello' aria-hidden=\"true\" ><\/span><\/span><\/p><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":900,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7973","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>impronta - OSG Ex-Cell-O<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osg-excello.com\/it\/impressum\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"impronta - OSG Ex-Cell-O\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osg-excello.com\/it\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"OSG Ex-Cell-O\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T05:20:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/impressum\\\/\",\"url\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/impressum\\\/\",\"name\":\"impronta - OSG Ex-Cell-O\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/#website\"},\"datePublished\":\"2019-11-19T07:50:55+00:00\",\"dateModified\":\"2025-07-03T05:20:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/impressum\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/osg-excello.com\\\/it\\\/impressum\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/impressum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"impronta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/\",\"name\":\"OSG Ex-Cell-O\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/#organization\",\"name\":\"OSG Ex-Cell-O GmbH\",\"url\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/osg-excello.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/osg_excello_logo_final-2.png\",\"contentUrl\":\"https:\\\/\\\/osg-excello.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/osg_excello_logo_final-2.png\",\"width\":514,\"height\":236,\"caption\":\"OSG Ex-Cell-O GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/osg-excello.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"impronta - OSG Ex-Cell-O","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osg-excello.com\/it\/impressum\/","og_locale":"it_IT","og_type":"article","og_title":"impronta - OSG Ex-Cell-O","og_url":"https:\/\/osg-excello.com\/it\/impressum\/","og_site_name":"OSG Ex-Cell-O","article_modified_time":"2025-07-03T05:20:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/osg-excello.com\/it\/impressum\/","url":"https:\/\/osg-excello.com\/it\/impressum\/","name":"impronta - OSG Ex-Cell-O","isPartOf":{"@id":"https:\/\/osg-excello.com\/it\/#website"},"datePublished":"2019-11-19T07:50:55+00:00","dateModified":"2025-07-03T05:20:19+00:00","breadcrumb":{"@id":"https:\/\/osg-excello.com\/it\/impressum\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osg-excello.com\/it\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/osg-excello.com\/it\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/osg-excello.com\/it\/"},{"@type":"ListItem","position":2,"name":"impronta"}]},{"@type":"WebSite","@id":"https:\/\/osg-excello.com\/it\/#website","url":"https:\/\/osg-excello.com\/it\/","name":"OSG Ex-Cell-O","description":"","publisher":{"@id":"https:\/\/osg-excello.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osg-excello.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/osg-excello.com\/it\/#organization","name":"OSG Ex-Cell-O GmbH","url":"https:\/\/osg-excello.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/osg-excello.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/osg-excello.com\/wp-content\/uploads\/2019\/11\/osg_excello_logo_final-2.png","contentUrl":"https:\/\/osg-excello.com\/wp-content\/uploads\/2019\/11\/osg_excello_logo_final-2.png","width":514,"height":236,"caption":"OSG Ex-Cell-O GmbH"},"image":{"@id":"https:\/\/osg-excello.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/osg-excello.com\/it\/wp-json\/wp\/v2\/pages\/7973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osg-excello.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/osg-excello.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/osg-excello.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/osg-excello.com\/it\/wp-json\/wp\/v2\/comments?post=7973"}],"version-history":[{"count":11,"href":"https:\/\/osg-excello.com\/it\/wp-json\/wp\/v2\/pages\/7973\/revisions"}],"predecessor-version":[{"id":16377,"href":"https:\/\/osg-excello.com\/it\/wp-json\/wp\/v2\/pages\/7973\/revisions\/16377"}],"wp:attachment":[{"href":"https:\/\/osg-excello.com\/it\/wp-json\/wp\/v2\/media?parent=7973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}